{"id":13638,"date":"2025-04-09T13:53:00","date_gmt":"2025-04-09T13:53:00","guid":{"rendered":"https:\/\/livingmultimediosde.net.ar\/INDEX\/?p=13638"},"modified":"2025-04-09T13:53:02","modified_gmt":"2025-04-09T13:53:02","slug":"preocupa-a-los-cardiologos-la-mortalidad-por-infarto-que-sigue-siendo-muy-alta","status":"publish","type":"post","link":"https:\/\/livingmultimediosde.net.ar\/INDEX\/2025\/04\/preocupa-a-los-cardiologos-la-mortalidad-por-infarto-que-sigue-siendo-muy-alta\/","title":{"rendered":"Preocupa a los cardi\u00f3logos la mortalidad por infarto que sigue siendo muy alta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Sociedad Argentina de Cardiolog\u00eda (SAC) expres\u00f3 su preocupaci\u00f3n debido a que no se logra reducir la mortalidad por enfermedades cardiovasculares en nuestro pa\u00eds. Muestra de ello es que se producen m\u00e1s de 50 mil infartos cada a\u00f1o y en gran medida debido a la falta de control de los factores de riesgo, como el colesterol, la hipertensi\u00f3n, la obesidad y el sedentarismo, entre otros, y por la escasa adherencia a los tratamientos farmacol\u00f3gicos en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La afirmaci\u00f3n fue realizada en el marco del D\u00eda de la Cardiolog\u00eda Argentina, que se conmemora este mi\u00e9rcoles 9 de abril, fecha establecida en homenaje a la Fundaci\u00f3n de la Sociedad Argentina de Cardiolog\u00eda, que se produjo en esa misma fecha en el a\u00f1o 1937, hace 88 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los especialistas de la SAC aseveran que a pesar de los avances en el manejo del infarto agudo de miocardio (IAM), la mortalidad en Argentina se mantiene alarmantemente alta, con un 8,5% seg\u00fan el \u00faltimo reporte del Registro Argentino de Infarto Agudo de Miocardio (ARGEN-IAM). Uno de los tratamientos m\u00e1s efectivos para reducir la mortalidad en estos casos es la reperfusi\u00f3n, que incluye la apertura de la arteria ocluida mediante v\u00edas farmacol\u00f3gicas (fibrinol\u00edticos) o mec\u00e1nicas (stents coronarios) dentro de las primeras 3 horas de iniciado los s\u00edntomas. Este indicador de mortalidad por infarto es clave para evaluar la calidad del sistema de salud de un pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas redes de infarto en Argentina han logrado optimizar los tiempos de reperfusi\u00f3n; sin embargo, esto sigue siendo un desaf\u00edo que requiere mejorar la interacci\u00f3n entre los sectores p\u00fablico y privado para abordar este grave problema de salud p\u00fablica\u201d, sostuvo el Dr. Pablo Stutzbach, presidente de la Sociedad Argentina de Cardiolog\u00eda (SAC).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan las cifras del \u00faltimo reporte de Estad\u00edsticas Vitales de la Direcci\u00f3n de Estad\u00edsticas e Informaci\u00f3n de Salud (DEIS) del Ministerio de Salud de la Naci\u00f3n, correspondientes al a\u00f1o 2023, en la Argentina fallecen cada a\u00f1o 99.454 personas por enfermedades cardiovasculares, lo que representa un 30,3% del total de decesos por causas definidas. Mientras que las enfermedades oncol\u00f3gicas representan el 19% del total de mortalidad anual, con 62.460 muertes anuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el grupo de las enfermedades cardiovasculares el DEIS incluye a la enfermedad hipertensiva, las enfermedades isqu\u00e9micas del coraz\u00f3n, la insuficiencia card\u00edaca, las complicaciones y descripciones mal definidas de enfermedad card\u00edaca, las dem\u00e1s enfermedades del coraz\u00f3n, las enfermedades cerebrovasculares, la aterosclerosis y las dem\u00e1s enfermedades del sistema circulatorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro dato llamativo es que, pese a la creencia popular de que la mortalidad cardiovascular es mayor en los hombres, ese mismo informe registra 50.025 decesos masculinos contra 49.417 mujeres fallecidas por esa causa durante dicho per\u00edodo, pr\u00e1cticamente la misma relaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una reciente encuesta de la SAC revel\u00f3 que el 45% de los cardi\u00f3logos y cl\u00ednicos en todo el pa\u00eds ha observado un aumento en el abandono del tratamiento con estatinas. Este abandono ha crecido considerablemente en los \u00faltimos meses, siendo las opiniones en redes sociales y los consejos de amigos y familiares las causas m\u00e1s frecuentes de desinformaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las estatinas son medicamentos fundamentales para controlar el colesterol y reducir el riesgo de infartos. Sin embargo, un n\u00famero alarmante de pacientes ha dejado de tomar este tratamiento o ha disminuido su dosis, influenciados por informaci\u00f3n err\u00f3nea que circula en redes sociales y otros medios fiables. Esto puede tener graves consecuencias para la salud cardiovascular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la SAC enfatizan: \u00abLas estatinas son cruciales en la prevenci\u00f3n del infarto y otros eventos cardiovasculares. La desinformaci\u00f3n puede tener consecuencias fatales\u201d. A pesar de la eficacia comprobada de las estatinas, es esencial que los pacientes sigan las indicaciones de sus m\u00e9dicos y no tomen decisiones basadas en mitos o rumores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dada la clara conexi\u00f3n entre el manejo eficaz del colesterol y la reducci\u00f3n del riesgo de infarto, es vital que la poblaci\u00f3n comprenda la importancia de mantener su medicaci\u00f3n seg\u00fan lo prescrito. \u00abComo m\u00e9dicos, debemos reforzar la educaci\u00f3n sobre los beneficios y riesgos de los medicamentos y desmentir la informaci\u00f3n err\u00f3nea que circula en nuestra sociedad\u00bb, subray\u00f3 el Dr. Sergio Baratta, vicepresidente de la SAC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La disminuci\u00f3n en la adherencia a los tratamientos con estatinas representa un riesgo considerable para la salud cardiovascular de la poblaci\u00f3n. Por ello, es imprescindible llevar a cabo campa\u00f1as de concientizaci\u00f3n que informen a la ciudadan\u00eda sobre:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El papel fundamental de las estatinas en la reducci\u00f3n del colesterol LDL y en la prevenci\u00f3n del IAM.<br>Los efectos secundarios reales asociados a su uso, en comparaci\u00f3n con los mitos populares que circulan.<br>La importancia de consultar a los m\u00e9dicos antes de realizar cualquier cambio en la medicaci\u00f3n.<br>Recomendaciones para la poblaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No interrumpir el tratamiento por iniciativa propia. Siempre consulte a su m\u00e9dico antes de realizar cambios en la medicaci\u00f3n.<br>Inf\u00f3rmese adecuadamente a trav\u00e9s de fuentes confiables sobre los beneficios de las estatinas y su rol en la prevenci\u00f3n del infarto.<br>Asista a chequeos m\u00e9dicos regulares para monitorear los niveles de colesterol y mantener su salud cardiovascular.<br>\u201cFrente a esta realidad, desde la Sociedad Argentina de Cardiolog\u00eda bregamos por mejorar la atenci\u00f3n de la enfermedad cardiovascular en todo el territorio de la Rep\u00fablica Argentina, buscando una mayor equidad en cuanto al acceso a una atenci\u00f3n profesional de excelencia y con la disponibilidad de equipamientos de diagn\u00f3stico y de tratamiento de calidad tanto en el sector p\u00fablico como en el privado\u201d, concluy\u00f3 el Dr. Stutzbach.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sociedad Argentina de Cardiolog\u00eda (SAC) expres\u00f3 su preocupaci\u00f3n debido a que no se logra reducir la mortalidad por enfermedades cardiovasculares en nuestro pa\u00eds. Muestra de ello es que se producen m\u00e1s de 50 mil infartos cada a\u00f1o y en gran medida debido a la falta de control de los factores de riesgo, como el colesterol, la hipertensi\u00f3n, la obesidad y el sedentarismo, entre otros, y por la escasa adherencia a los tratamientos farmacol\u00f3gicos en general. La afirmaci\u00f3n fue realizada en el marco del D\u00eda de la Cardiolog\u00eda Argentina, que&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-13638","post","type-post","status-publish","format-standard","hentry","category-interes-general"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"rober","author_link":"https:\/\/livingmultimediosde.net.ar\/INDEX\/author\/rober\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/livingmultimediosde.net.ar\/INDEX\/category\/interes-general\/\" rel=\"category tag\">INTERES GENERAL<\/a>","rttpg_excerpt":"La Sociedad Argentina de Cardiolog\u00eda (SAC) expres\u00f3 su preocupaci\u00f3n debido a que no se logra reducir la mortalidad por enfermedades cardiovasculares en nuestro pa\u00eds. Muestra de ello es que se producen m\u00e1s de 50 mil infartos cada a\u00f1o y en gran medida debido a la falta de control de los factores de riesgo, como el&hellip;","_links":{"self":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts\/13638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/comments?post=13638"}],"version-history":[{"count":1,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts\/13638\/revisions"}],"predecessor-version":[{"id":13640,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts\/13638\/revisions\/13640"}],"wp:attachment":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/media?parent=13638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/categories?post=13638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/tags?post=13638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}