{"id":12263,"date":"2025-01-03T01:42:57","date_gmt":"2025-01-03T01:42:57","guid":{"rendered":"https:\/\/livingmultimediosde.net.ar\/INDEX\/?p=12263"},"modified":"2025-01-03T01:43:01","modified_gmt":"2025-01-03T01:43:01","slug":"arca-controlara-transferencias-en-billeteras-virtuales-cual-es-el-monto-minimo-alcanzado","status":"publish","type":"post","link":"https:\/\/livingmultimediosde.net.ar\/INDEX\/2025\/01\/arca-controlara-transferencias-en-billeteras-virtuales-cual-es-el-monto-minimo-alcanzado\/","title":{"rendered":"ARCA controlar\u00e1 transferencias en billeteras virtuales: cu\u00e1l es el monto m\u00ednimo alcanzado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Agencia de Recaudaci\u00f3n y Control Aduanero (ARCA) actualiz\u00f3 los montos a partir de los cuales las entidades financieras y las billeteras virtuales deben informar sobre las transacciones, saldos y consumos de sus clientes. La medida no afecta a los consumidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta actualizaci\u00f3n semestral se basa en las variaciones del \u00cdndice de Precios al Consumidor (IPC) del INDEC.<br>Desde el 1\u00b0 de enero deben informarse las siguientes operaciones solo si superan los siguientes importes:<br>$600.000:<br>Total de consumos con tarjetas de d\u00e9bito del pa\u00eds.<br>Ingresos o egresos totales en billeteras virtuales.<br>$1.000.000:<br>Total de acreditaciones bancarias registradas en el mes.<br>Total de dep\u00f3sitos a plazo constituidos en el mes.<br>Extracciones en efectivo en el pa\u00eds o en el exterior, por ventanilla, cajero autom\u00e1tico o cualquier otro medio.<br>Saldo final en cuentas bancarias al \u00faltimo d\u00eda h\u00e1bil de cada mes.<br>Saldo final en billeteras virtuales al \u00faltimo d\u00eda h\u00e1bil de cada mes.<br>$2.000.000:<br>Aplicable solo para billeteras virtuales, en caso de transferencias bancarias o virtuales superiores a dicho monto.<br>La medida no afecta a los consumidores ya que es un r\u00e9gimen de informaci\u00f3n que deben cumplir las entidades financieras, billeteras virtuales y plataformas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Agencia de Recaudaci\u00f3n y Control Aduanero (ARCA) actualiz\u00f3 los montos a partir de los cuales las entidades financieras y las billeteras virtuales deben informar sobre las transacciones, saldos y consumos de sus clientes. La medida no afecta a los consumidores. Esta actualizaci\u00f3n semestral se basa en las variaciones del \u00cdndice de Precios al Consumidor (IPC) del INDEC.Desde el 1\u00b0 de enero deben informarse las siguientes operaciones solo si superan los siguientes importes:$600.000:Total de consumos con tarjetas de d\u00e9bito del pa\u00eds.Ingresos o egresos totales en billeteras virtuales.$1.000.000:Total de acreditaciones bancarias&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-12263","post","type-post","status-publish","format-standard","hentry","category-interes-general"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"rober","author_link":"https:\/\/livingmultimediosde.net.ar\/INDEX\/author\/rober\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/livingmultimediosde.net.ar\/INDEX\/category\/interes-general\/\" rel=\"category tag\">INTERES GENERAL<\/a>","rttpg_excerpt":"La Agencia de Recaudaci\u00f3n y Control Aduanero (ARCA) actualiz\u00f3 los montos a partir de los cuales las entidades financieras y las billeteras virtuales deben informar sobre las transacciones, saldos y consumos de sus clientes. La medida no afecta a los consumidores. Esta actualizaci\u00f3n semestral se basa en las variaciones del \u00cdndice de Precios al Consumidor&hellip;","_links":{"self":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts\/12263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/comments?post=12263"}],"version-history":[{"count":1,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts\/12263\/revisions"}],"predecessor-version":[{"id":12265,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/posts\/12263\/revisions\/12265"}],"wp:attachment":[{"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/media?parent=12263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/categories?post=12263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livingmultimediosde.net.ar\/INDEX\/wp-json\/wp\/v2\/tags?post=12263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}